{"id":3626,"date":"2025-07-25T07:21:02","date_gmt":"2025-07-25T06:21:02","guid":{"rendered":"https:\/\/zelenedoline.si\/edamec-v-kosu\/"},"modified":"2026-04-14T08:03:24","modified_gmt":"2026-04-14T07:03:24","slug":"edamec-pieces","status":"publish","type":"product","link":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/","title":{"rendered":"Edamec pieces"},"content":{"rendered":"<p>Discover the premium and popular Edamec Zelene Doline cheese, made exclusively from Slovenian farm milk, perfect for adding variety to many dishes.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>Edamec Zelene Doline is distinguished by its mild, gentle, and clean flavour<\/li>\n<li>produced <strong>exclusively from Slovenian milk<\/strong><\/li>\n<li>natural source of protein and calcium<\/li>\n<li>rennet is of <strong>microbial origin<\/strong> (suitable for lacto-vegetarian diets)<\/li>\n<li><strong>lactose-free <em>(lactose content is &lt; 0.1g per 100g of product)<\/em><\/strong><\/li>\n<li>preservative-free, also without lysozyme<\/li>\n<li>holder of the <strong>Higher Quality<\/strong> designation<\/li>\n<li>carries the \u201cSelected Quality Slovenia\u201d label<\/li>\n<\/ul>\n","protected":false},"featured_media":848,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[125],"product_cat":[99,98],"product_tag":[101,100],"class_list":{"0":"post-3626","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-zelene-doline","7":"product_cat-cheeses","8":"product_cat-lactose-free","9":"product_tag-cheese","10":"product_tag-lactose-free","12":"first","13":"instock","14":"shipping-taxable","15":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edamec pieces - Zelene Doline<\/title>\n<meta name=\"description\" content=\"Discover the premium and popular Edamec Zelene Doline cheese, made exclusively from Slovenian farm milk, perfect for adding variety to many dishes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zelenedoline.si\/en\/edamec-pieces\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edamec pieces - Zelene Doline\" \/>\n<meta property=\"og:description\" content=\"Discover the premium and popular Edamec Zelene Doline cheese, made exclusively from Slovenian farm milk, perfect for adding variety to many dishes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zelenedoline.si\/en\/edamec-pieces\/\" \/>\n<meta property=\"og:site_name\" content=\"Zelene Doline\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T07:03:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/\",\"name\":\"Edamec pieces - Zelene Doline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png\",\"datePublished\":\"2025-07-25T06:21:02+00:00\",\"dateModified\":\"2026-04-14T07:03:24+00:00\",\"description\":\"Discover the premium and popular Edamec Zelene Doline cheese, made exclusively from Slovenian farm milk, perfect for adding variety to many dishes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png\",\"contentUrl\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png\",\"width\":2000,\"height\":1448,\"caption\":\"Edamec Zelene Doline\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/edamec-pieces\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Edamec pieces\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\",\"name\":\"Zelene Doline\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#organization\",\"name\":\"Zelene Doline\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.a7268a.svg\",\"contentUrl\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.a7268a.svg\",\"width\":102,\"height\":102,\"caption\":\"Zelene Doline\"},\"image\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edamec pieces - Zelene Doline","description":"Discover the premium and popular Edamec Zelene Doline cheese, made exclusively from Slovenian farm milk, perfect for adding variety to many dishes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/","og_locale":"en_US","og_type":"article","og_title":"Edamec pieces - Zelene Doline","og_description":"Discover the premium and popular Edamec Zelene Doline cheese, made exclusively from Slovenian farm milk, perfect for adding variety to many dishes.","og_url":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/","og_site_name":"Zelene Doline","article_modified_time":"2026-04-14T07:03:24+00:00","og_image":[{"width":2000,"height":1448,"url":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/","url":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/","name":"Edamec pieces - Zelene Doline","isPartOf":{"@id":"https:\/\/zelenedoline.si\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/#primaryimage"},"image":{"@id":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/#primaryimage"},"thumbnailUrl":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png","datePublished":"2025-07-25T06:21:02+00:00","dateModified":"2026-04-14T07:03:24+00:00","description":"Discover the premium and popular Edamec Zelene Doline cheese, made exclusively from Slovenian farm milk, perfect for adding variety to many dishes.","breadcrumb":{"@id":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zelenedoline.si\/en\/edamec-pieces\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/#primaryimage","url":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png","contentUrl":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_sir_edamec_300g_2000x1448-2000x1448-1.png","width":2000,"height":1448,"caption":"Edamec Zelene Doline"},{"@type":"BreadcrumbList","@id":"https:\/\/zelenedoline.si\/en\/edamec-pieces\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zelenedoline.si\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/zelenedoline.si\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Edamec pieces"}]},{"@type":"WebSite","@id":"https:\/\/zelenedoline.si\/en\/#website","url":"https:\/\/zelenedoline.si\/en\/","name":"Zelene Doline","description":"","publisher":{"@id":"https:\/\/zelenedoline.si\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zelenedoline.si\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zelenedoline.si\/en\/#organization","name":"Zelene Doline","url":"https:\/\/zelenedoline.si\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zelenedoline.si\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/10\/logo.a7268a.svg","contentUrl":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/10\/logo.a7268a.svg","width":102,"height":102,"caption":"Zelene Doline"},"image":{"@id":"https:\/\/zelenedoline.si\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product\/3626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/comments?post=3626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/media\/848"}],"wp:attachment":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/media?parent=3626"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_brand?post=3626"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_cat?post=3626"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_tag?post=3626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}