{"id":3644,"date":"2025-07-25T10:26:00","date_gmt":"2025-07-25T09:26:00","guid":{"rendered":"https:\/\/zelenedoline.si\/ribani-sir-zelene-doline\/"},"modified":"2026-05-06T16:44:44","modified_gmt":"2026-05-06T15:44:44","slug":"grated-cheese-zelene-doline","status":"publish","type":"product","link":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/","title":{"rendered":"Grated Cheese Zelene Doline"},"content":{"rendered":"<p>Zelene Doline Grated Cheese is made for culinary indulgence and is perfect for making pizza or gratin dishes.<\/p>\n","protected":false},"excerpt":{"rendered":"<ul>\n<li>created for gratin and other dishes, as well as making pizza<\/li>\n<li>made <strong>exclusively from Slovenian milk<\/strong><\/li>\n<li>source of calcium<\/li>\n<li>natural source of protein<\/li>\n<li><strong>lactose-free <em>(lactose content is &lt; 0.1g per 100g of product)<\/em><\/strong><\/li>\n<li><strong>preservative-free<\/strong><\/li>\n<li>carries the<strong> \u201cSelected Quality Slovenia\u201d<\/strong> label<\/li>\n<\/ul>\n","protected":false},"featured_media":2815,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[125],"product_cat":[99,98],"product_tag":[100],"class_list":{"0":"post-3644","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-zelene-doline","7":"product_cat-cheeses","8":"product_cat-lactose-free","9":"product_tag-lactose-free","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grated Cheese Zelene Doline - Zelene Doline<\/title>\n<meta name=\"description\" content=\"Zelene Doline Grated Cheese is made for culinary indulgence and is perfect for making pizza or gratin dishes.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grated Cheese Zelene Doline - Zelene Doline\" \/>\n<meta property=\"og:description\" content=\"Zelene Doline Grated Cheese is made for culinary indulgence and is perfect for making pizza or gratin dishes.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/\" \/>\n<meta property=\"og:site_name\" content=\"Zelene Doline\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T15:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_mesani_ribani_sir_2021.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1108\" \/>\n\t<meta property=\"og:image:height\" content=\"1665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/\",\"name\":\"Grated Cheese Zelene Doline - Zelene Doline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/300g_mesani_ribani_sir_2021.png\",\"datePublished\":\"2025-07-25T09:26:00+00:00\",\"dateModified\":\"2026-05-06T15:44:44+00:00\",\"description\":\"Zelene Doline Grated Cheese is made for culinary indulgence and is perfect for making pizza or gratin dishes.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/300g_mesani_ribani_sir_2021.png\",\"contentUrl\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/300g_mesani_ribani_sir_2021.png\",\"width\":1108,\"height\":1665},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/grated-cheese-zelene-doline\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grated Cheese Zelene Doline\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\",\"name\":\"Zelene Doline\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#organization\",\"name\":\"Zelene Doline\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.a7268a.svg\",\"contentUrl\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.a7268a.svg\",\"width\":102,\"height\":102,\"caption\":\"Zelene Doline\"},\"image\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grated Cheese Zelene Doline - Zelene Doline","description":"Zelene Doline Grated Cheese is made for culinary indulgence and is perfect for making pizza or gratin dishes.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/","og_locale":"en_US","og_type":"article","og_title":"Grated Cheese Zelene Doline - Zelene Doline","og_description":"Zelene Doline Grated Cheese is made for culinary indulgence and is perfect for making pizza or gratin dishes.\u00a0","og_url":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/","og_site_name":"Zelene Doline","article_modified_time":"2026-05-06T15:44:44+00:00","og_image":[{"width":1108,"height":1665,"url":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_mesani_ribani_sir_2021.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/","url":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/","name":"Grated Cheese Zelene Doline - Zelene Doline","isPartOf":{"@id":"https:\/\/zelenedoline.si\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/#primaryimage"},"image":{"@id":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/#primaryimage"},"thumbnailUrl":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_mesani_ribani_sir_2021.png","datePublished":"2025-07-25T09:26:00+00:00","dateModified":"2026-05-06T15:44:44+00:00","description":"Zelene Doline Grated Cheese is made for culinary indulgence and is perfect for making pizza or gratin dishes.\u00a0","breadcrumb":{"@id":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/#primaryimage","url":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_mesani_ribani_sir_2021.png","contentUrl":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/07\/300g_mesani_ribani_sir_2021.png","width":1108,"height":1665},{"@type":"BreadcrumbList","@id":"https:\/\/zelenedoline.si\/en\/grated-cheese-zelene-doline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zelenedoline.si\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/zelenedoline.si\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Grated Cheese Zelene Doline"}]},{"@type":"WebSite","@id":"https:\/\/zelenedoline.si\/en\/#website","url":"https:\/\/zelenedoline.si\/en\/","name":"Zelene Doline","description":"","publisher":{"@id":"https:\/\/zelenedoline.si\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zelenedoline.si\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zelenedoline.si\/en\/#organization","name":"Zelene Doline","url":"https:\/\/zelenedoline.si\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zelenedoline.si\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/10\/logo.a7268a.svg","contentUrl":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/10\/logo.a7268a.svg","width":102,"height":102,"caption":"Zelene Doline"},"image":{"@id":"https:\/\/zelenedoline.si\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product\/3644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/comments?post=3644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/media\/2815"}],"wp:attachment":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/media?parent=3644"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_brand?post=3644"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_cat?post=3644"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_tag?post=3644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}