{"id":109,"count":6,"description":"Oki Doki is the cheekiest drop of milk in the fairy-tale land of Okilandia. There it creates the most delicious dairy products with his hard-working helpers.","link":"https:\/\/zelenedoline.si\/en\/for-children\/","name":"For Children","slug":"for-children","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Okusni &amp; Zdravi I Mle\u010dni izdelki za otroke - Zelene Doline<\/title>\n<meta name=\"description\" content=\"Spoznajte izdelke Zelenih Dolin, namensko zasnovane za otroke vseh starosti. Z njimi lahko zdravo za\u010dnete dan in ga tudi zaklju\u010dite.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zelenedoline.si\/en\/for-children\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Okusni &amp; Zdravi I Mle\u010dni izdelki za otroke - Zelene Doline\" \/>\n<meta property=\"og:description\" content=\"Spoznajte izdelke Zelenih Dolin, namensko zasnovane za otroke vseh starosti. Z njimi lahko zdravo za\u010dnete dan in ga tudi zaklju\u010dite.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zelenedoline.si\/en\/for-children\/\" \/>\n<meta property=\"og:site_name\" content=\"Zelene Doline\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/for-children\\\/\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/for-children\\\/\",\"name\":\"Okusni & Zdravi I Mle\u010dni izdelki za otroke - Zelene Doline\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#website\"},\"description\":\"Spoznajte izdelke Zelenih Dolin, namensko zasnovane za otroke vseh starosti. Z njimi lahko zdravo za\u010dnete dan in ga tudi zaklju\u010dite.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/for-children\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/for-children\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"For Children\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\",\"name\":\"Zelene Doline\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#organization\",\"name\":\"Zelene Doline\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.a7268a.svg\",\"contentUrl\":\"https:\\\/\\\/zelenedoline.si\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/logo.a7268a.svg\",\"width\":102,\"height\":102,\"caption\":\"Zelene Doline\"},\"image\":{\"@id\":\"https:\\\/\\\/zelenedoline.si\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Okusni & Zdravi I Mle\u010dni izdelki za otroke - Zelene Doline","description":"Spoznajte izdelke Zelenih Dolin, namensko zasnovane za otroke vseh starosti. Z njimi lahko zdravo za\u010dnete dan in ga tudi zaklju\u010dite.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zelenedoline.si\/en\/for-children\/","og_locale":"en_US","og_type":"article","og_title":"Okusni & Zdravi I Mle\u010dni izdelki za otroke - Zelene Doline","og_description":"Spoznajte izdelke Zelenih Dolin, namensko zasnovane za otroke vseh starosti. Z njimi lahko zdravo za\u010dnete dan in ga tudi zaklju\u010dite.","og_url":"https:\/\/zelenedoline.si\/en\/for-children\/","og_site_name":"Zelene Doline","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zelenedoline.si\/en\/for-children\/","url":"https:\/\/zelenedoline.si\/en\/for-children\/","name":"Okusni & Zdravi I Mle\u010dni izdelki za otroke - Zelene Doline","isPartOf":{"@id":"https:\/\/zelenedoline.si\/en\/#website"},"description":"Spoznajte izdelke Zelenih Dolin, namensko zasnovane za otroke vseh starosti. Z njimi lahko zdravo za\u010dnete dan in ga tudi zaklju\u010dite.","breadcrumb":{"@id":"https:\/\/zelenedoline.si\/en\/for-children\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zelenedoline.si\/en\/for-children\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zelenedoline.si\/en\/"},{"@type":"ListItem","position":2,"name":"For Children"}]},{"@type":"WebSite","@id":"https:\/\/zelenedoline.si\/en\/#website","url":"https:\/\/zelenedoline.si\/en\/","name":"Zelene Doline","description":"","publisher":{"@id":"https:\/\/zelenedoline.si\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zelenedoline.si\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zelenedoline.si\/en\/#organization","name":"Zelene Doline","url":"https:\/\/zelenedoline.si\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zelenedoline.si\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/10\/logo.a7268a.svg","contentUrl":"https:\/\/zelenedoline.si\/wp-content\/uploads\/2025\/10\/logo.a7268a.svg","width":102,"height":102,"caption":"Zelene Doline"},"image":{"@id":"https:\/\/zelenedoline.si\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_cat\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/zelenedoline.si\/en\/wp-json\/wp\/v2\/product?product_cat=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}